{"id":7388,"date":"2021-08-06T13:58:10","date_gmt":"2021-08-06T16:58:10","guid":{"rendered":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/?p=7388"},"modified":"2021-08-06T13:58:10","modified_gmt":"2021-08-06T16:58:10","slug":"francimara-e-frederico-acompanham-agenda-do-governador-claudio-castro-em-campos","status":"publish","type":"post","link":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/2021\/08\/06\/francimara-e-frederico-acompanham-agenda-do-governador-claudio-castro-em-campos\/","title":{"rendered":"Francimara e Frederico acompanham agenda do governador Cl\u00e1udio Castro em Campos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7389\" src=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/08\/francimara-frederico-1024x1024.jpg\" alt=\"\" width=\"800\" height=\"800\" \/><\/p>\n<p style=\"text-align: justify;\">A Prefeita de S\u00e3o Francisco de Itabapoana, Francimara Barbosa Lemos, e o seu esposo, Frederico Barbosa Lemos, acompanham a agenda do governador Cl\u00e1udio Castro em Campos dos Goytacazes. O vice-prefeito, Raliston Souza tamb\u00e9m participa do encontro.<\/p>\n<p style=\"text-align: justify;\">Castro trouxe para o interior do estado o programa Governo Presente, onde cumpre agenda em cidades do norte e noroeste, anunciando investimentos do governo estadual.<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Em Campos dos Goytacazes ao lado de nossa prefeita Francimara, vice-prefeito Raliston Souza e o prefeito de Campos amigo Wladimir recebendo o governador Cl\u00e1udio Castro. Obrigado governador por olhar nosso interior com carinho. Quando temos o interior forte, temos um estado forte. Pra frente que se anda!&#8221;<\/em>, disse Frederico Barbosa Lemos nas redes sociais.<\/p>\n<p style=\"text-align: justify;\">O governador vai a S\u00e3o Francisco do Itabapoana neste s\u00e1bado (7), e participar\u00e1 do F\u00f3rum Regional de Lideran\u00e7as Femininas, que ser\u00e1 realizado, de 10h \u00e0s 12h, no Complexo Cultural do munic\u00edpio, no Centro.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Ffrederico.souzabarbosalemos%2Fposts%2F995511007864548&amp;show_text=true&amp;width=500\" width=\"500\" height=\"721\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Leia tamb\u00e9m: <a href=\"https:\/\/www.tribunanf.com.br\/sfi-sedia-forum-regional-de-liderancas-femininas-com-a-presenca-do-governador-claudio-castro\/\">SFI sedia F\u00f3rum Regional de Lideran\u00e7as Femininas com a presen\u00e7a do governador Cl\u00e1udio Castro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeita de S\u00e3o Francisco de Itabapoana, Francimara Barbosa Lemos, e o seu esposo, Frederico Barbosa Lemos, acompanham a agenda&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-7388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/08\/francimara-frederico-e1628269054856.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/7388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/comments?post=7388"}],"version-history":[{"count":0,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/7388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media\/7389"}],"wp:attachment":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media?parent=7388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/categories?post=7388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/tags?post=7388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}