{"id":14743,"date":"2025-08-07T18:45:50","date_gmt":"2025-08-07T21:45:50","guid":{"rendered":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/?p=14743"},"modified":"2025-08-07T18:45:50","modified_gmt":"2025-08-07T21:45:50","slug":"camara-aprova-medida-que-permite-pagar-bonus-a-servidor-para-tentar-diminuir-fila-do-inss","status":"publish","type":"post","link":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/2025\/08\/07\/camara-aprova-medida-que-permite-pagar-bonus-a-servidor-para-tentar-diminuir-fila-do-inss\/","title":{"rendered":"C\u00e2mara aprova medida que permite pagar b\u00f4nus a servidor para tentar diminuir fila do INSS"},"content":{"rendered":"<figure id=\"attachment_10456\" aria-describedby=\"caption-attachment-10456\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10456\" src=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep-1024x613.jpg\" alt=\"\" width=\"800\" height=\"479\" srcset=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep-1024x613.jpg 1024w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep-300x179.jpg 300w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep-768x459.jpg 768w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep.jpg 1170w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-10456\" class=\"wp-caption-text\">Pal\u00e1cio do Congresso Nacional na Esplanada dos Minist\u00e9rios em Bras\u00edlia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">A C\u00e2mara dos Deputados aprovou, nesta quinta-feira (dia 7), a medida provis\u00f3ria (MP) do governo federal que pretender reduzir a fila de atendimento do INSS, agilizando a revis\u00e3o de benef\u00edcios. A aprova\u00e7\u00e3o aconteceu ap\u00f3s parlamentares de oposi\u00e7\u00e3o tentarem obstruir as vota\u00e7\u00f5es. Em junho, havia 2,44 milh\u00f5es de requerimentos \u00e0 espera de an\u00e1lise.<\/p>\n<p style=\"text-align: justify;\">Para revisar e reavaliar benef\u00edcios previdenci\u00e1rios, a proposta cria o &#8220;Programa de Gerenciamento de Benef\u00edcios&#8221; com o pagamento de um benef\u00edcio extraordin\u00e1rio aos servidores.<\/p>\n<p style=\"text-align: justify;\">Publicada pelo presidente Luiz In\u00e1cio Lula da Silva em 15 de abril, ela precisa ser aprovada no Congresso antes de 12 de agosto. O texto segue agora para o Senado.<\/p>\n<p style=\"text-align: justify;\">A medida provis\u00f3ria prev\u00ea R$ 68 por processo conclu\u00eddo e tamb\u00e9m R$ 78 por per\u00edcia ou an\u00e1lise documental realizada. Os valores s\u00e3o semelhantes aos pagos at\u00e9 dezembro de 2024. O programa contar\u00e1 com a participa\u00e7\u00e3o volunt\u00e1ria de servidores do INSS e da Per\u00edcia M\u00e9dica Federal.<\/p>\n<p style=\"text-align: justify;\">A prioridade ser\u00e3o processos pendentes h\u00e1 mais de 45 dias ou com prazo judicial expirado. Tamb\u00e9m ser\u00e3o contempladas per\u00edcias m\u00e9dicas realizadas em unidades sem oferta regular de servi\u00e7o, com agendamento superior a 30 dias ou prazo judicial vencido, e avalia\u00e7\u00f5es sociais voltadas ao Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC\/Loas).<\/p>\n<p style=\"text-align: justify;\">Validade<br \/>\nO programa ter\u00e1 validade inicial de 12 meses e pode ser prorrogado uma vez, desde que n\u00e3o ultrapasse o prazo final de 31 de dezembro de 2026.<\/p>\n<p style=\"text-align: justify;\">A MP estabelece que a participa\u00e7\u00e3o dos servidores no programa n\u00e3o pode prejudicar os atendimentos regulares da Previd\u00eancia Social.<\/p>\n<p style=\"text-align: justify;\">Os pagamentos ainda est\u00e3o sujeitos \u00e0 autoriza\u00e7\u00e3o or\u00e7ament\u00e1ria anual. Tamb\u00e9m haver\u00e1 um ato conjunto dos minist\u00e9rios da Previd\u00eancia, Gest\u00e3o P\u00fablica e Casa Civil para definir detalhes operacionais, como crit\u00e9rios de ades\u00e3o, prioriza\u00e7\u00e3o de processos e limites de pagamento.<\/p>\n<p style=\"text-align: justify;\">De acordo com estudo da Secretaria de Monitoramento e Avalia\u00e7\u00e3o de Pol\u00edticas P\u00fablicas e Assuntos Econ\u00f4micos do Minist\u00e9rio do Planejamento e Or\u00e7amento (MPO), est\u00e1 prevista economia de R$ 4,58 bilh\u00f5es anuais ap\u00f3s completada a revis\u00e3o de 2,4 milh\u00f5es de benef\u00edcios assistenciais.<\/p>\n<p style=\"text-align: justify;\">Emendas<\/p>\n<p style=\"text-align: justify;\">A relatora, senadora Zenaide Maia (PSD-RN), acatou tr\u00eas das 30 emendas apresentadas ao texto original do Executivo. As emendas determinam a divulga\u00e7\u00e3o peri\u00f3dica das metas e dos resultados do programa nos portais oficiais do Minist\u00e9rio da Previd\u00eancia Social e do INSS. Estabelecem ainda que o programa deve utilizar tecnologias acess\u00edveis para comunica\u00e7\u00e3o com os benefici\u00e1rios, facilitando seu uso e inclus\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A fila de espera do INSS fechou o ano de 2024 com 2,042 milh\u00f5es de requerimentos por benef\u00edcios sociais e da Previd\u00eancia. \u00c9 o maior n\u00famero de requerimentos aguardando an\u00e1lise em todo o governo Luiz In\u00e1cio Lula da Silva, que na campanha prometeu acabar com a fila. Em junho, essa fila subiu para 2,443 milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Extra*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados aprovou, nesta quinta-feira (dia 7), a medida provis\u00f3ria (MP) do governo federal que pretender reduzir a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":10456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-14743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2022\/11\/camara-dep.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/14743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/comments?post=14743"}],"version-history":[{"count":2,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/14743\/revisions"}],"predecessor-version":[{"id":14745,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/14743\/revisions\/14745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media\/10456"}],"wp:attachment":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media?parent=14743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/categories?post=14743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/tags?post=14743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}