{"id":12689,"date":"2024-03-22T09:14:26","date_gmt":"2024-03-22T12:14:26","guid":{"rendered":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/?p=12689"},"modified":"2024-03-22T09:14:26","modified_gmt":"2024-03-22T12:14:26","slug":"prefeito-abraaozinho-lidera-a-intencao-de-votos-em-nilopolis-mostra-parana-pesquisas","status":"publish","type":"post","link":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/2024\/03\/22\/prefeito-abraaozinho-lidera-a-intencao-de-votos-em-nilopolis-mostra-parana-pesquisas\/","title":{"rendered":"Prefeito Abra\u00e3ozinho lidera a inten\u00e7\u00e3o de votos em Nil\u00f3polis, mostra Paran\u00e1 Pesquisas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12691\" src=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_-1024x576.jpg\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_-1024x576.jpg 1024w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_-300x169.jpg 300w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_-768x432.jpg 768w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_.jpg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">O prefeito de Nil\u00f3polis, Abra\u00e3ozinho, lidera pesquisa de inten\u00e7\u00e3o de votos divulgada nesta sexta-feira pelo Instituto Paran\u00e1. Em todos os cen\u00e1rios, ele aparece com uma frente confort\u00e1vel diante dos poss\u00edveis concorrentes. Na hip\u00f3tese com maior n\u00fameros de candidatos, Abra\u00e3ozinho tem 48,2%; Jorge Sessim, 9,9% ; Alessandro Calazans, 7,4% ; Rog\u00e9rio Ribeiro, 7,4%\u00a8; Dedinho, 4,6%; Zeca Carvalho do PT, 1,8% e Leandro Silva, 1,0%.<\/p>\n<p style=\"text-align: justify;\">Em cen\u00e1rios mais enxutos, o atual prefeito ultrapassa a marca dos 50%. Veja os n\u00fameros com apenas tr\u00eas candidatos: Abra\u00e3ozinho, 52,8%; S\u00e9rgio Sessim, 13,1% e Ricardo Ribeiro, 11,3%.<\/p>\n<p style=\"text-align: justify;\">Em um cen\u00e1rio de confronto direto com apenas o segundo colocado, os n\u00fameros s\u00e3o: Abra\u00e3ozinho 59,1% e S\u00e9rgio Sessim, 17,2.<\/p>\n<p style=\"text-align: justify;\">Num enfrentamento direto com Rog\u00e9rio Ribeiro, Abraaozinho teria 62,2% contra 16,5% do advers\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 contra Alessandro Calazans, Abra\u00e3ozinho teria 62,6% e o oponente 15,9%<\/p>\n<p style=\"text-align: justify;\">Alessandro Calazans tem 35,4% de rejei\u00e7\u00e3o: Dedinho, 28,7%, S\u00e9rgio Sessim, 18,4%, Abra\u00e3ozinho, 16,0%; Zeca Carvalho do PT, 16,0%. Rog\u00e9rio Ribeiro, 11,5% e Leandro Silva, 10,7%<\/p>\n<p style=\"text-align: justify;\">De acordo com a Resolu\u00e7\u00e3o-TSE n.\u00ba 23.600\/2019, essa pesquisa est\u00e1 registrada no Tribunal Superior Eleitoral sob o n.\u00ba RJ00779\/2024 para o cargo de Prefeito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12690\" src=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/Captura-de-Tela-2024-03-22-as-07.14.59_Easy-Resize.com_-1024x634.jpg\" alt=\"\" width=\"800\" height=\"495\" srcset=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/Captura-de-Tela-2024-03-22-as-07.14.59_Easy-Resize.com_-1024x634.jpg 1024w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/Captura-de-Tela-2024-03-22-as-07.14.59_Easy-Resize.com_-300x186.jpg 300w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/Captura-de-Tela-2024-03-22-as-07.14.59_Easy-Resize.com_-768x476.jpg 768w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/Captura-de-Tela-2024-03-22-as-07.14.59_Easy-Resize.com_.jpg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Fonte: Agenda do Poder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Nil\u00f3polis, Abra\u00e3ozinho, lidera pesquisa de inten\u00e7\u00e3o de votos divulgada nesta sexta-feira pelo Instituto Paran\u00e1. Em todos os&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-12689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2024\/03\/abraaozinho-1067x600-1_Easy-Resize.com_.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/12689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/comments?post=12689"}],"version-history":[{"count":0,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/12689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media\/12691"}],"wp:attachment":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media?parent=12689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/categories?post=12689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/tags?post=12689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}