{"id":12047,"date":"2023-11-24T17:54:04","date_gmt":"2023-11-24T20:54:04","guid":{"rendered":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/?p=12047"},"modified":"2023-11-24T18:07:23","modified_gmt":"2023-11-24T21:07:23","slug":"tce-rj-determina-suspensao-de-pagamentos-a-os-que-atua-na-area-da-saude-de-diversos-municipios","status":"publish","type":"post","link":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/2023\/11\/24\/tce-rj-determina-suspensao-de-pagamentos-a-os-que-atua-na-area-da-saude-de-diversos-municipios\/","title":{"rendered":"TCE-RJ determina  suspens\u00e3o de pagamentos a OS que atua na \u00e1rea da Sa\u00fade de diversos munic\u00edpios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7127\" src=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/06\/tce.jpg\" alt=\"\" width=\"768\" height=\"432\" srcset=\"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/06\/tce.jpg 768w, https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/06\/tce-300x169.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Foram verificados ind\u00edcios de irregularidades em contrata\u00e7\u00f5es de Cachoeiras de Macacu, Santa Maria Madalena, S\u00e3o Gon\u00e7alo e Saquarema<\/em><\/p>\n<p style=\"text-align: justify;\">Por meio de decis\u00e3o monocr\u00e1tica da conselheira Mariana Montebello Willeman, o Tribunal de Contas do Estado do Rio de Janeiro (TCE-RJ) determinou aos secret\u00e1rios de Sa\u00fade dos Munic\u00edpios de Cachoeiras de Macacu, Santa Maria Madalena, S\u00e3o Gon\u00e7alo e Saquarema o n\u00e3o reconhecimento de despesas e a interrup\u00e7\u00e3o imediata de pagamentos \u00e0 Organiza\u00e7\u00e3o Social (OS) Projeto Social Cresce Comunidade &#8211; Prima Qualit\u00e1 destinados a contrata\u00e7\u00f5es com suspeitas de irregularidades. A decis\u00e3o foi proferida no dia 22 de novembro e atendeu a representa\u00e7\u00e3o formulada pela Coordenadoria de Auditoria de Pol\u00edticas em Sa\u00fade (CAD-Sa\u00fade), da Secretaria-Geral de Controle Externo. Ao longo de auditoria de conformidade, foi verificado que a rela\u00e7\u00e3o contratual estabelecida pelos munic\u00edpios com a OS violou os princ\u00edpios da impessoalidade, da moralidade e da probidade administrativa, afrontando \u00e0 legisla\u00e7\u00e3o de reg\u00eancia das OS\u2019s.<\/p>\n<p style=\"text-align: justify;\">Entre outros pontos que levaram ao deferimento da tutela provis\u00f3ria, chamaram aten\u00e7\u00e3o do Corpo Instrutivo tr\u00eas contrata\u00e7\u00f5es da OS nos quatro munic\u00edpios. A sociedade empres\u00e1ria Bozza e Guerra Consultoria e Servi\u00e7os de Sa\u00fade LTDA., por exemplo, foi contratada quatro dias ap\u00f3s sua funda\u00e7\u00e3o sem pr\u00e9via sele\u00e7\u00e3o pela organiza\u00e7\u00e3o social Prima Qualit\u00e1. J\u00e1 os s\u00f3cios do escrit\u00f3rio Moraes e Matos Advogados, contratado para servi\u00e7os jur\u00eddicos consultivos e contenciosos trabalhistas, tem entre seus s\u00f3cios dois integrantes do conselho de administra\u00e7\u00e3o da OS.<\/p>\n<p style=\"text-align: justify;\">Outra contrata\u00e7\u00e3o, esta firmada para loca\u00e7\u00e3o de ve\u00edculos junto \u00e0 sociedade empres\u00e1ria Ssantana Com\u00e9rcio de Ve\u00edculos e Servi\u00e7os LTDA., apresentou alguns fatos configuradores de ind\u00edcios de direcionamento. De acordo com a an\u00e1lise da CAD-Sa\u00fade, a empresa foi constitu\u00edda dias antes de ser convidada para o processo seletivo e seus s\u00f3cios mantinham v\u00ednculos com os administradores da OS, inclusive partid\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Com o apoio da unidade de controle interno e da assessoria jur\u00eddica de cada Munic\u00edpio, os secret\u00e1rios de Sa\u00fade dever\u00e3o, dentro de 15 dias, cumprir as determina\u00e7\u00f5es previstas na decis\u00e3o monocr\u00e1tica, tais como apurar responsabilidades legais, regulamentares e contratuais cab\u00edveis ante os fatos descritos na representa\u00e7\u00e3o, devendo informar ao TCE-RJ as provid\u00eancias que est\u00e3o sendo adotadas.<\/p>\n<p style=\"font-weight: 300; text-align: justify;\"><a href=\"https:\/\/www.tcerj.tc.br\/portal-tce-webapi\/api\/arquivos\/04cb7f52-1b3c-47dd-01fb-08dbeb5803a4\/download\" target=\"_blank\" rel=\"noopener\"><b><strong>Confira a \u00edntegra da decis\u00e3o monocr\u00e1tica<\/strong><\/b><\/a><\/p>\n<p style=\"text-align: justify;\">Fonte: TCE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram verificados ind\u00edcios de irregularidades em contrata\u00e7\u00f5es de Cachoeiras de Macacu, Santa Maria Madalena, S\u00e3o Gon\u00e7alo e Saquarema Por meio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-12047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-content\/uploads\/sites\/11\/2021\/06\/tce.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/12047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/comments?post=12047"}],"version-history":[{"count":0,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/posts\/12047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media\/7127"}],"wp:attachment":[{"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/media?parent=12047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/categories?post=12047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribunanf.com.br\/blogdoralfereis\/wp-json\/wp\/v2\/tags?post=12047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}